{"id":460,"date":"2020-02-25T14:35:00","date_gmt":"2020-02-25T14:35:00","guid":{"rendered":"https:\/\/magentostaging.colleamoi.com\/blogue\/?p=460"},"modified":"2022-05-19T20:15:23","modified_gmt":"2022-05-19T20:15:23","slug":"les-formes","status":"publish","type":"post","link":"https:\/\/colleamoi.com\/blogue\/les-formes\/","title":{"rendered":"Les formes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Pour s&rsquo;amuser \u00e0 colorier et pratiquer les formes g\u00e9om\u00e9triques en m\u00eame temps. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le mat\u00e9riel: <br>&#8211; Des cartons<br>&#8211; Colle en b\u00e2ton<br>&#8211; Ciseaux<br>&#8211; B\u00e2tons de bois<br>&#8211; Crayons \u00e0 colorier<br>&#8211; Le pdf \u00e0 imprimer: <a href=\"https:\/\/bit.ly\/3dumbt5\">https:\/\/bit.ly\/3dumbt5<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9tapes:<br>&#8211; Coller les formes sur un carton.<br>&#8211; Colorier-les.<br>&#8211; Colorier le nombre de b\u00e2tons correspondants aux nombres de c\u00f4t\u00e9 de la forme. <br>&#8211; R\u00e9p\u00e9ter pour chaque forme.<br>&#8211; D\u00e9couper les formes.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amusez-vous \u00e0 comparer les formes, compter les c\u00f4t\u00e9s et apprendre les noms de celles-ci.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-prise-en-charge-des-contenus-embarques wp-block-embed-prise-en-charge-des-contenus-embarques wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Activit\u00e9 pour apprendre les formes\" width=\"1250\" height=\"938\" src=\"https:\/\/www.youtube.com\/embed\/ovdqD3ELwdU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Pour s&rsquo;amuser \u00e0 colorier et pratiquer les formes g\u00e9om\u00e9triques en m\u00eame temps. Le mat\u00e9riel: &#8211; Des cartons&#8211; Colle en b\u00e2ton&#8211; Ciseaux&#8211; B\u00e2tons de bois&#8211; Crayons \u00e0 colorier&#8211; Le pdf \u00e0&#8230;<\/p>\n","protected":false},"author":2,"featured_media":462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,16],"tags":[],"class_list":["post-460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bricolage","category-dessins-a-telecharger"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les formes - Colle \u00e0 moi<\/title>\n<meta name=\"description\" content=\"Bricolage pour enfant 5-7 ans pour s&#039;amuser \u00e0 colorier et pratiquer les formes g\u00e9om\u00e9triques en m\u00eame temps.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colleamoi.com\/blogue\/les-formes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les formes\" \/>\n<meta property=\"og:description\" content=\"Bricolage pour enfant 5-7 ans pour s&#039;amuser \u00e0 colorier et pratiquer les formes g\u00e9om\u00e9triques en m\u00eame temps.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colleamoi.com\/blogue\/les-formes\/\" \/>\n<meta property=\"og:site_name\" content=\"Colle \u00e0 moi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/colleamoi\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-25T14:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-19T20:15:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/05\/bricolage-avec-les-formes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Colle \u00e0 moi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Colle \u00e0 moi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/\"},\"author\":{\"name\":\"Colle \u00e0 moi\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#\\\/schema\\\/person\\\/08effc938d5e57771b2a32c504bd3ffa\"},\"headline\":\"Les formes\",\"datePublished\":\"2020-02-25T14:35:00+00:00\",\"dateModified\":\"2022-05-19T20:15:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/\"},\"wordCount\":102,\"publisher\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/bricolage-avec-les-formes.jpg\",\"articleSection\":[\"Bricolage\",\"Dessins \u00e0 t\u00e9l\u00e9charger\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/\",\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/\",\"name\":\"Les formes - Colle \u00e0 moi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/bricolage-avec-les-formes.jpg\",\"datePublished\":\"2020-02-25T14:35:00+00:00\",\"dateModified\":\"2022-05-19T20:15:23+00:00\",\"description\":\"Bricolage pour enfant 5-7 ans pour s'amuser \u00e0 colorier et pratiquer les formes g\u00e9om\u00e9triques en m\u00eame temps.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/bricolage-avec-les-formes.jpg\",\"contentUrl\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/bricolage-avec-les-formes.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Bricolage enfant formes g\u00e9om\u00e9trique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/les-formes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les formes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#website\",\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/\",\"name\":\"Colle \u00e0 moi\",\"description\":\"Restons coll\u00e9s ensemble!\",\"publisher\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#organization\",\"name\":\"Colle \u00e0 moi\",\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/magentostaging.colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-Group-588-e1651238780891.png\",\"contentUrl\":\"https:\\\/\\\/magentostaging.colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-Group-588-e1651238780891.png\",\"width\":400,\"height\":130,\"caption\":\"Colle \u00e0 moi\"},\"image\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/colleamoi\\\/?ref=br_rs\",\"https:\\\/\\\/www.instagram.com\\\/colleamoi\\\/?hl=fr-ca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#\\\/schema\\\/person\\\/08effc938d5e57771b2a32c504bd3ffa\",\"name\":\"Colle \u00e0 moi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d829b35e3e9e2abe4fb8e7dc19a93ca15b6cf3f44d75957f5a8fbddabe91c728?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d829b35e3e9e2abe4fb8e7dc19a93ca15b6cf3f44d75957f5a8fbddabe91c728?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d829b35e3e9e2abe4fb8e7dc19a93ca15b6cf3f44d75957f5a8fbddabe91c728?s=96&d=mm&r=g\",\"caption\":\"Colle \u00e0 moi\"},\"sameAs\":[\"https:\\\/\\\/colleamoi.com\\\/\"],\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/author\\\/adeldegan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les formes - Colle \u00e0 moi","description":"Bricolage pour enfant 5-7 ans pour s'amuser \u00e0 colorier et pratiquer les formes g\u00e9om\u00e9triques en m\u00eame temps.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colleamoi.com\/blogue\/les-formes\/","og_locale":"fr_FR","og_type":"article","og_title":"Les formes","og_description":"Bricolage pour enfant 5-7 ans pour s'amuser \u00e0 colorier et pratiquer les formes g\u00e9om\u00e9triques en m\u00eame temps.","og_url":"https:\/\/colleamoi.com\/blogue\/les-formes\/","og_site_name":"Colle \u00e0 moi","article_publisher":"https:\/\/www.facebook.com\/colleamoi\/?ref=br_rs","article_published_time":"2020-02-25T14:35:00+00:00","article_modified_time":"2022-05-19T20:15:23+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/05\/bricolage-avec-les-formes.jpg","type":"image\/jpeg"}],"author":"Colle \u00e0 moi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Colle \u00e0 moi","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/#article","isPartOf":{"@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/"},"author":{"name":"Colle \u00e0 moi","@id":"https:\/\/colleamoi.com\/blogue\/#\/schema\/person\/08effc938d5e57771b2a32c504bd3ffa"},"headline":"Les formes","datePublished":"2020-02-25T14:35:00+00:00","dateModified":"2022-05-19T20:15:23+00:00","mainEntityOfPage":{"@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/"},"wordCount":102,"publisher":{"@id":"https:\/\/colleamoi.com\/blogue\/#organization"},"image":{"@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/#primaryimage"},"thumbnailUrl":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/05\/bricolage-avec-les-formes.jpg","articleSection":["Bricolage","Dessins \u00e0 t\u00e9l\u00e9charger"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/","url":"https:\/\/colleamoi.com\/blogue\/les-formes\/","name":"Les formes - Colle \u00e0 moi","isPartOf":{"@id":"https:\/\/colleamoi.com\/blogue\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/#primaryimage"},"image":{"@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/#primaryimage"},"thumbnailUrl":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/05\/bricolage-avec-les-formes.jpg","datePublished":"2020-02-25T14:35:00+00:00","dateModified":"2022-05-19T20:15:23+00:00","description":"Bricolage pour enfant 5-7 ans pour s'amuser \u00e0 colorier et pratiquer les formes g\u00e9om\u00e9triques en m\u00eame temps.","breadcrumb":{"@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colleamoi.com\/blogue\/les-formes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/#primaryimage","url":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/05\/bricolage-avec-les-formes.jpg","contentUrl":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/05\/bricolage-avec-les-formes.jpg","width":1200,"height":630,"caption":"Bricolage enfant formes g\u00e9om\u00e9trique"},{"@type":"BreadcrumbList","@id":"https:\/\/colleamoi.com\/blogue\/les-formes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/colleamoi.com\/blogue\/"},{"@type":"ListItem","position":2,"name":"Les formes"}]},{"@type":"WebSite","@id":"https:\/\/colleamoi.com\/blogue\/#website","url":"https:\/\/colleamoi.com\/blogue\/","name":"Colle \u00e0 moi","description":"Restons coll\u00e9s ensemble!","publisher":{"@id":"https:\/\/colleamoi.com\/blogue\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colleamoi.com\/blogue\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/colleamoi.com\/blogue\/#organization","name":"Colle \u00e0 moi","url":"https:\/\/colleamoi.com\/blogue\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/colleamoi.com\/blogue\/#\/schema\/logo\/image\/","url":"https:\/\/magentostaging.colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/cropped-cropped-Group-588-e1651238780891.png","contentUrl":"https:\/\/magentostaging.colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/cropped-cropped-Group-588-e1651238780891.png","width":400,"height":130,"caption":"Colle \u00e0 moi"},"image":{"@id":"https:\/\/colleamoi.com\/blogue\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/colleamoi\/?ref=br_rs","https:\/\/www.instagram.com\/colleamoi\/?hl=fr-ca"]},{"@type":"Person","@id":"https:\/\/colleamoi.com\/blogue\/#\/schema\/person\/08effc938d5e57771b2a32c504bd3ffa","name":"Colle \u00e0 moi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d829b35e3e9e2abe4fb8e7dc19a93ca15b6cf3f44d75957f5a8fbddabe91c728?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d829b35e3e9e2abe4fb8e7dc19a93ca15b6cf3f44d75957f5a8fbddabe91c728?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d829b35e3e9e2abe4fb8e7dc19a93ca15b6cf3f44d75957f5a8fbddabe91c728?s=96&d=mm&r=g","caption":"Colle \u00e0 moi"},"sameAs":["https:\/\/colleamoi.com\/"],"url":"https:\/\/colleamoi.com\/blogue\/author\/adeldegan\/"}]}},"_links":{"self":[{"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/posts\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/comments?post=460"}],"version-history":[{"count":2,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/posts\/460\/revisions"}],"predecessor-version":[{"id":836,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/posts\/460\/revisions\/836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/media\/462"}],"wp:attachment":[{"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/media?parent=460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/categories?post=460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/tags?post=460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}