{"id":12,"date":"2022-04-27T21:15:49","date_gmt":"2022-04-27T21:15:49","guid":{"rendered":"https:\/\/magentostaging.colleamoi.com\/blog\/?p=12"},"modified":"2022-05-06T17:15:44","modified_gmt":"2022-05-06T17:15:44","slug":"impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps","status":"publish","type":"post","link":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/","title":{"rendered":"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps"},"content":{"rendered":"\n<p>Vous avez d\u00e9j\u00e0 commenc\u00e9 le grand m\u00e9nage du printemps ou vous y pensez depuis quelques semaines&nbsp;? Avouons-le, c\u2019est juste plus simple de passer \u00e0 travers quand les enfants ne sont pas dans nos jambes. Si jamais vous \u00eates pr\u00eat(e)s \u00e0 impliquer tous les membres de la famille, voici quelques trucs pour que tout se passe dans la joie et l\u2019harmonie (ou du moins dans le plaisir)&nbsp;!&nbsp; En d\u00e9l\u00e9guant les t\u00e2ches des enfants selon leur \u00e2ge, ainsi que leurs comp\u00e9tences, vous pourrez certainement commencer leur \u00e9ducation d\u00e8s 2 ans. Pour ceux et celles qui d\u00e9sirent inclure leurs bouts de choux dans cette activit\u00e9, voici quelques trucs&nbsp;<\/p>\n\n\n\n<p><strong>1. Pourquoi inclure mon enfant dans le m\u00e9nage&nbsp;?<\/strong><\/p>\n\n\n\n<p>Tout d\u2019abord, en laissant vos enfants vous aider, vous d\u00e9montrez que vous avez confiance en eux et en leurs capacit\u00e9s. En plus, vous leur apprenez tr\u00e8s t\u00f4t que le m\u00e9nage ne se fait pas par magie&nbsp;! Bien \u00e9videmment que tous les enfants ne r\u00e9agiront pas tous de fa\u00e7on positive, mais en commen\u00e7ant par des t\u00e2ches rapides et en augmentant tranquillement la complexit\u00e9, la routine prendra forme sans douleur.<\/p>\n\n\n\n<p><strong>2. Comment initier mon enfant aux t\u00e2ches m\u00e9nag\u00e8res<\/strong><\/p>\n\n\n\n<p>Plus t\u00f4t on investit du temps \u00e0 l\u2019\u00e9ducation aux t\u00e2ches m\u00e9nag\u00e8res, plus facile, \u00e7a devient&nbsp;! Pour commencer, il est recommand\u00e9 de donner des t\u00e2ches simples et quotidiennes afin d\u2019int\u00e9grer cela dans la routine. On se brosse les dents tous les jours, non&nbsp;? Alors, pourquoi ne pas faire son lit tous les matins&nbsp;?<\/p>\n\n\n\n<p>Allez-y, selon vos priorit\u00e9s familiales. Si jamais vous d\u00e9sirez int\u00e9grer des t\u00e2ches dans la routine quotidienne de vos enfants, les tableaux de&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.minimomotivation.com\/produit\/ado-de-moins-de-5-ans\/\" target=\"_blank\">Minimo<\/a>&nbsp;aident \u00e0 d\u00e9velopper l\u2019autonomie et stimule la confiance des enfants gr\u00e2ce \u00e0 des aimants qu\u2019ils peuvent glisser sur leur tableau une fois la t\u00e2che accomplie.<\/p>\n\n\n\n<p><strong>3. Comment rendre le m\u00e9nage du printemps amusant&nbsp;?<\/strong><\/p>\n\n\n\n<p>\u00c7a, c\u2019est la partie la plus difficile&nbsp;! Premi\u00e8rement, il faut montrer l\u2019exemple. \u00c9viter d\u2019appr\u00e9hender verbalement le moment du dit m\u00e9nage. Ensuite, cr\u00e9ez une ambiance sp\u00e9ciale. Par exemple, vous pourriez monter le volume de la musique, chantez et dansez en m\u00eame que nettoyer. Vous pouvez fournir des \u00e9couteurs si la famille ne s\u2019entend pas sur la trame sonore.<\/p>\n\n\n\n<p>Il est \u00e9galement important d\u2019expliquer et clarifier les t\u00e2ches \u00e0 vos cocos avant de commencer. Au d\u00e9but vous aurez l\u2019impression qu\u2019il est plus long d\u2019expliquer que de faire vous-m\u00eame, c\u2019est normal.<\/p>\n\n\n\n<p>Durant la session de m\u00e9nage, on peut les encourager et les f\u00e9liciter pour leur participation.<\/p>\n\n\n\n<p><strong>4. Comment r\u00e9agir si le travail n\u2019est pas \u00e0 votre go\u00fbt&nbsp;?<\/strong><\/p>\n\n\n\n<p>On n\u2019en parle pas&nbsp;! On focus sur le r\u00e9sultat avec des commentaires comme&nbsp;: \u2018\u2019Je me sens tellement bien quand la maison est propre&nbsp;!\u2019\u2019. Durant l\u2019apprentissage les r\u00e9sultats ne comptent pas, c\u2019est la participation active qui devrait \u00eatre soulign\u00e9e. Au fil des semaines, si l\u2019on maintient la routine, il y aura certainement une am\u00e9lioration.<\/p>\n\n\n\n<p><strong>5. Quelle t\u00e2che m\u00e9nag\u00e8re mon enfant peut-il accomplir?<\/strong><\/p>\n\n\n\n<p>Voici une liste des t\u00e2ches propos\u00e9e par Na\u00eetre et grandir pour les enfants&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/naitreetgrandir.com\/fr\/etape\/3-5-ans\/vie-famille\/fiche.aspx?doc=ik-naitre-grandir-faire-participer-enfant-corvee-tache-menagere\" target=\"_blank\">moins de 5 ans<\/a>, ou pour les&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/naitreetgrandir.com\/fr\/etape\/5-8-ans\/vie-famille\/fiche.aspx?doc=taches-menageres\" target=\"_blank\">5 ans et plus<\/a>. Pour vous faciliter la t\u00e2che, voici la liste ci-dessous:<\/p>\n\n\n\n<p><em><strong>Avant 3&nbsp;ans<\/strong><\/em><\/p>\n\n\n\n<p>\u2013 Ranger ses jouets. Au d\u00e9but, votre enfant aura besoin de votre aide. Petit \u00e0 petit, vous pourrez le laisser en faire un peu plus.<br>\u2013 Trouver les chaussettes semblables parmi celles qui sortent de la s\u00e9cheuse afin que vous puissiez les assembler.<br>\u2013 Plier des d\u00e9barbouillettes et faire une pile.<br>\u2013 Placer ses bottes ou ses souliers \u00e0 c\u00f4t\u00e9 de la porte d\u2019entr\u00e9e.<br>\u2013 Accrocher son manteau \u00e0 un crochet qui est \u00e0 sa hauteur.<br>\u2013 Nettoyer la table ou d\u2019autres objets avec un linge humide.<br>\u2013 Mettre un d\u00e9chet dans la poubelle.<br>\u2013 Laver des l\u00e9gumes, d\u00e9chirer des feuilles de laitue, verser des ingr\u00e9dients dans un bol.<br>\u2013 Placer des livres dans une biblioth\u00e8que basse.<\/p>\n\n\n\n<p><em><strong>De 3&nbsp;ans \u00e0 5&nbsp;ans<\/strong><\/em><\/p>\n\n\n\n<p>\u2013 Ranger ses jouets.<br>\u2013 Mettre ses v\u00eatements sales dans le panier \u00e0 linge.<br>\u2013 D\u00e9poser ses v\u00eatements pli\u00e9s dans un tiroir \u00e0 sa port\u00e9e.<br>\u2013 Mettre sa vaisselle sale sur le comptoir, pr\u00e8s du lavabo.<br>\u2013 Mesurer les ingr\u00e9dients secs d\u2019une recette, verser dans un bol et m\u00e9langer.<br>\u2013 Aider \u00e0 mettre la table en pla\u00e7ant les ustensiles et les serviettes de table.<br>\u2013 D\u00e9neiger le balcon avec une petite pelle, s\u2019il n\u2019y a pas trop de neige.<br>\u2013 Passer le balai sous la table apr\u00e8s le repas.<br>\u2013 Arroser les plantes, avec votre supervision.<\/p>\n\n\n\n<p><em><strong>De 5 \u00e0 6&nbsp;ans<\/strong><\/em><\/p>\n\n\n\n<p>\u2013 Mettre la table pour le repas.<br>\u2013 Ramasser sa vaisselle sale et la ranger dans le lave-vaisselle.<br>\u2013 D\u00e9poser ses v\u00eatements sales dans le panier \u00e0 linge.<br>\u2013 Ranger les bas propres (en les mettant en paire).<br>\u2013 Plier les serviettes propres.<br>\u2013 Essuyer la poussi\u00e8re sur une \u00e9tag\u00e8re avec un linge.<br>\u2013 Arroser les plantes de la maison.<\/p>\n\n\n\n<p><em><strong>De 7 \u00e0 8&nbsp;ans<\/strong><\/em><\/p>\n\n\n\n<p>\u2013 Participer \u00e0 l\u2019\u00e9picerie (aider \u00e0 d\u00e9poser des articles dans le panier, porter des sacs l\u00e9gers).<br>\u2013 Faire son lit.<br>\u2013 Plier et ranger ses v\u00eatements.<br>\u2013 Mettre le linge \u00e0 s\u00e9cher sur le s\u00e9choir \u00e0 linge.<br>\u2013 Balayer ou passer l\u2019aspirateur.<br>\u2013 Aider \u00e0 la pr\u00e9paration du repas.<br>\u2013 Aider \u00e0 nettoyer la vaisselle.<br>\u2013 Vider le lave-vaisselle.<br>\u2013 Pr\u00e9parer son lunch du lendemain pour l\u2019\u00e9cole.<br>\u2013 Sortir les ordures.<br>\u2013 Arracher les mauvaises herbes.<br>\u2013 Nourrir les animaux de compagnie de la famille.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous avez d\u00e9j\u00e0 commenc\u00e9 le grand m\u00e9nage du printemps ou vous y pensez depuis quelques semaines ? Avouons-le, c\u2019est juste plus simple de passer \u00e0 travers quand les enfants ne sont pas dans nos jambes. Si jamais vous \u00eates pr\u00eat(e)s \u00e0 impliquer tous les membres de la famille, voici quelques trucs pour que tout se passe dans la joie et l\u2019harmonie (ou du moins dans le plaisir) !<\/p>\n","protected":false},"author":6,"featured_media":14,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-12","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps - Colle \u00e0 moi<\/title>\n<meta name=\"description\" content=\"Pour ceux et celles qui d\u00e9sirent inclure leurs bouts de choux dans leur m\u00e9nage de printemps ou quotidien, voici quelques trucs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps\" \/>\n<meta property=\"og:description\" content=\"Pour ceux et celles qui d\u00e9sirent inclure leurs bouts de choux dans leur m\u00e9nage de printemps ou quotidien, voici quelques trucs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/\" \/>\n<meta property=\"og:site_name\" content=\"Colle \u00e0 moi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/colleamoi\/?ref=br_rs\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-27T21:15:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-06T17:15:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/GettyImages-1092271420.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandra Baronian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandra Baronian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/\"},\"author\":{\"name\":\"Alexandra Baronian\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#\\\/schema\\\/person\\\/f18b6f7349c2b29c6a1b711bd110fc1e\"},\"headline\":\"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps\",\"datePublished\":\"2022-04-27T21:15:49+00:00\",\"dateModified\":\"2022-05-06T17:15:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/\"},\"wordCount\":969,\"publisher\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GettyImages-1092271420.jpeg\",\"articleSection\":[\"\u00c9ducation\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/\",\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/\",\"name\":\"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps - Colle \u00e0 moi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GettyImages-1092271420.jpeg\",\"datePublished\":\"2022-04-27T21:15:49+00:00\",\"dateModified\":\"2022-05-06T17:15:44+00:00\",\"description\":\"Pour ceux et celles qui d\u00e9sirent inclure leurs bouts de choux dans leur m\u00e9nage de printemps ou quotidien, voici quelques trucs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GettyImages-1092271420.jpeg\",\"contentUrl\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GettyImages-1092271420.jpeg\",\"width\":1200,\"height\":630,\"caption\":\"Quand un enfant peut-il apprendre?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#website\",\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/\",\"name\":\"Colle \u00e0 moi\",\"description\":\"Restons coll\u00e9s ensemble!\",\"publisher\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#organization\",\"name\":\"Colle \u00e0 moi\",\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/magentostaging.colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-Group-588-e1651238780891.png\",\"contentUrl\":\"https:\\\/\\\/magentostaging.colleamoi.com\\\/blogue\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-Group-588-e1651238780891.png\",\"width\":400,\"height\":130,\"caption\":\"Colle \u00e0 moi\"},\"image\":{\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/colleamoi\\\/?ref=br_rs\",\"https:\\\/\\\/www.instagram.com\\\/colleamoi\\\/?hl=fr-ca\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/#\\\/schema\\\/person\\\/f18b6f7349c2b29c6a1b711bd110fc1e\",\"name\":\"Alexandra Baronian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ebb8e1c9afdae5db7a0151ee325240a61f66f6379e6abdd30bbdd097d2de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ebb8e1c9afdae5db7a0151ee325240a61f66f6379e6abdd30bbdd097d2de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ebb8e1c9afdae5db7a0151ee325240a61f66f6379e6abdd30bbdd097d2de?s=96&d=mm&r=g\",\"caption\":\"Alexandra Baronian\"},\"url\":\"https:\\\/\\\/colleamoi.com\\\/blogue\\\/author\\\/alexandra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps - Colle \u00e0 moi","description":"Pour ceux et celles qui d\u00e9sirent inclure leurs bouts de choux dans leur m\u00e9nage de printemps ou quotidien, voici quelques trucs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/","og_locale":"fr_FR","og_type":"article","og_title":"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps","og_description":"Pour ceux et celles qui d\u00e9sirent inclure leurs bouts de choux dans leur m\u00e9nage de printemps ou quotidien, voici quelques trucs.","og_url":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/","og_site_name":"Colle \u00e0 moi","article_publisher":"https:\/\/www.facebook.com\/colleamoi\/?ref=br_rs","article_published_time":"2022-04-27T21:15:49+00:00","article_modified_time":"2022-05-06T17:15:44+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/GettyImages-1092271420.jpeg","type":"image\/jpeg"}],"author":"Alexandra Baronian","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alexandra Baronian","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/#article","isPartOf":{"@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/"},"author":{"name":"Alexandra Baronian","@id":"https:\/\/colleamoi.com\/blogue\/#\/schema\/person\/f18b6f7349c2b29c6a1b711bd110fc1e"},"headline":"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps","datePublished":"2022-04-27T21:15:49+00:00","dateModified":"2022-05-06T17:15:44+00:00","mainEntityOfPage":{"@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/"},"wordCount":969,"publisher":{"@id":"https:\/\/colleamoi.com\/blogue\/#organization"},"image":{"@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/#primaryimage"},"thumbnailUrl":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/GettyImages-1092271420.jpeg","articleSection":["\u00c9ducation"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/","url":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/","name":"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps - Colle \u00e0 moi","isPartOf":{"@id":"https:\/\/colleamoi.com\/blogue\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/#primaryimage"},"image":{"@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/#primaryimage"},"thumbnailUrl":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/GettyImages-1092271420.jpeg","datePublished":"2022-04-27T21:15:49+00:00","dateModified":"2022-05-06T17:15:44+00:00","description":"Pour ceux et celles qui d\u00e9sirent inclure leurs bouts de choux dans leur m\u00e9nage de printemps ou quotidien, voici quelques trucs.","breadcrumb":{"@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/#primaryimage","url":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/GettyImages-1092271420.jpeg","contentUrl":"https:\/\/colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/GettyImages-1092271420.jpeg","width":1200,"height":630,"caption":"Quand un enfant peut-il apprendre?"},{"@type":"BreadcrumbList","@id":"https:\/\/colleamoi.com\/blogue\/impliquer-les-enfants-dans-les-taches-menageres-du-printemps-ou-en-tout-temps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/colleamoi.com\/blogue\/"},{"@type":"ListItem","position":2,"name":"Impliquer les enfants dans les t\u00e2ches m\u00e9nag\u00e8res du printemps\u2026 ou en tout temps"}]},{"@type":"WebSite","@id":"https:\/\/colleamoi.com\/blogue\/#website","url":"https:\/\/colleamoi.com\/blogue\/","name":"Colle \u00e0 moi","description":"Restons coll\u00e9s ensemble!","publisher":{"@id":"https:\/\/colleamoi.com\/blogue\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colleamoi.com\/blogue\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/colleamoi.com\/blogue\/#organization","name":"Colle \u00e0 moi","url":"https:\/\/colleamoi.com\/blogue\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/colleamoi.com\/blogue\/#\/schema\/logo\/image\/","url":"https:\/\/magentostaging.colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/cropped-cropped-Group-588-e1651238780891.png","contentUrl":"https:\/\/magentostaging.colleamoi.com\/blogue\/wp-content\/uploads\/2022\/04\/cropped-cropped-Group-588-e1651238780891.png","width":400,"height":130,"caption":"Colle \u00e0 moi"},"image":{"@id":"https:\/\/colleamoi.com\/blogue\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/colleamoi\/?ref=br_rs","https:\/\/www.instagram.com\/colleamoi\/?hl=fr-ca"]},{"@type":"Person","@id":"https:\/\/colleamoi.com\/blogue\/#\/schema\/person\/f18b6f7349c2b29c6a1b711bd110fc1e","name":"Alexandra Baronian","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5f53ebb8e1c9afdae5db7a0151ee325240a61f66f6379e6abdd30bbdd097d2de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f53ebb8e1c9afdae5db7a0151ee325240a61f66f6379e6abdd30bbdd097d2de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f53ebb8e1c9afdae5db7a0151ee325240a61f66f6379e6abdd30bbdd097d2de?s=96&d=mm&r=g","caption":"Alexandra Baronian"},"url":"https:\/\/colleamoi.com\/blogue\/author\/alexandra\/"}]}},"_links":{"self":[{"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/posts\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":2,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/posts\/12\/revisions"}],"predecessor-version":[{"id":83,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/posts\/12\/revisions\/83"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/media\/14"}],"wp:attachment":[{"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/media?parent=12"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/categories?post=12"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colleamoi.com\/blogue\/wp-json\/wp\/v2\/tags?post=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}